{"id":4003,"date":"2018-06-19T16:58:21","date_gmt":"2018-06-19T19:58:21","guid":{"rendered":"https:\/\/liraodonto.com.br\/?p=4003"},"modified":"2018-06-19T17:09:06","modified_gmt":"2018-06-19T20:09:06","slug":"festa-junina-cuidados-com-os-alimentos-tipicos-dessa-temporada","status":"publish","type":"post","link":"https:\/\/liraodonto.com.br\/es\/festa-junina-cuidados-com-os-alimentos-tipicos-dessa-temporada\/","title":{"rendered":"Festa junina \u2013 cuidados com os alimentos t\u00edpicos dessa temporada"},"content":{"rendered":"<p>Num piscar de olhos chegamos ao meio do ano! Ufa, j\u00e1? O m\u00eas de junho nos traz, al\u00e9m do friozinho, as festas juninas. Tempo bom para brincar, recordar a inf\u00e2ncia com dan\u00e7as, m\u00fasicas &#8220;olha a cobra&#8230; \u00e9 mentira!&#8221; e principalmente, deliciosas comidas e bebidas t\u00edpicas.<\/p>\n<p>Alguns cuidados b\u00e1sicos, podem evitar uma visita extra ao dentista. Ent\u00e3o, para garantir que sua festa termine bem, sem preju\u00edzos nem &#8220;janelas&#8221;, daremos algumas sugest\u00f5es de cuidados b\u00e1sicos que podem evitar pequenos acidentes dentais entre as mordidas irresist\u00edveis em cada prato t\u00edpico.<\/p>\n<p><strong>Espiga de milho <\/strong><\/p>\n<p>O cuidado com esse alimento \u00e9 especificamente sobre comer o milho direto na espiga. H\u00e1 risco de que poss\u00edveis reparos odontol\u00f3gicos realizados anteriormente sejam danificados. Para quem usa aparelho ortod\u00f4ntico ent\u00e3o o alerta \u00e9 maior, pois o contato da espiga com as pe\u00e7as que comp\u00f5em esse tipo de aparelho pode enroscar, puxar e at\u00e9 quebrar alguma parte. Portanto, o ideal \u00e9 raspar o milho para retir\u00e1-lo da espiga antes de com\u00ea-lo.<\/p>\n<p><strong>Ma\u00e7\u00e3 do amor<\/strong><\/p>\n<p>Em caso de dentes sens\u00edveis, tanto os que est\u00e3o sendo tratados quanto os que ainda est\u00e3o doloridos, morder uma ma\u00e7\u00e3 do amor pode virar uma tortura. E para quem usa aparelho ortod\u00f4ntico a ma\u00e7\u00e3 \u00e9 uma tarefa praticamente imposs\u00edvel. A dica, nesses casos, \u00e9 cortar a ma\u00e7\u00e3 (do amor ou n\u00e3o) em peda\u00e7os menores para evitar o desconforto.<\/p>\n<p>Tamb\u00e9m \u00e9 importante lembrar que ap\u00f3s a ingest\u00e3o de a\u00e7\u00facar, em qualquer ocasi\u00e3o, tomar \u00e1gua ajuda a soltar os res\u00edduos de alimentos dos dentes, evitando a c\u00e1rie.<\/p>\n<p>Quer saber mais sobre c\u00e1rie? <a href=\"https:\/\/liraodonto.com.br\/es\/incidencia-de-caries-no-brasil\/\">Leia essa mat\u00e9ria<\/a>.<\/p>\n<p><strong>Pipoca <\/strong><\/p>\n<p>Presente no cinema, no encontro com os amigos, a pipoca \u00e9 muito mais frequente do que t\u00edpica. Ent\u00e3o, os cuidados aqui s\u00e3o bem importantes o ano todo!<\/p>\n<p>A pipoca requer um cuidado especial porque pode deixar casquinhas do milho entre os dentes, podendo aumentar a produ\u00e7\u00e3o de bact\u00e9ria. Ou seja, ap\u00f3s o consumo \u00e9 necess\u00e1rio escova\u00e7\u00e3o e fio dental. Caso tenha d\u00favida sobre a utiliza\u00e7\u00e3o do fio dental, <a href=\"https:\/\/liraodonto.com.br\/es\/qual-principal-importancia-do-uso-do-fio-dental\/\">clique aqui<\/a>.<\/p>\n<p>Outro cuidado com a pipoca \u00e9 com os gr\u00e3os que n\u00e3o estouram por completo, os famosos piru\u00e1s ou mururus. Muitas pessoas tem o h\u00e1bito de mastigar esses gr\u00e3os e isso pode rachar e at\u00e9 quebrar o dente. Para quem est\u00e1 em tratamento ortod\u00f4ntico o cuidado triplica, pois, o gr\u00e3o tamb\u00e9m pode danificar o aparelho.<\/p>\n<p><strong>Pinh\u00e3o<\/strong><\/p>\n<p>\u00c9 bem comum que as pessoas acabem utilizando os dentes para ajudar a descascar o pinh\u00e3o, claro que isso pode prejudicar a sa\u00fade bucal de diversas formas. Farpinhas ou peda\u00e7os de casca podem ficar entre os dentes machucando a gengiva, ocasionando ac\u00famulo de bact\u00e9rias e at\u00e9 fazendo voc\u00ea passar vergonha na hora do anarri\u00ea.<\/p>\n<p>O ideal \u00e9 que o pinh\u00e3o seja descascado com um descascador, ou qualquer outro instrumento que te auxilie. Fora que nunca \u00e9 aconselh\u00e1vel que se descasque qualquer tipo de alimento com os dentes, pois h\u00e1 o risco de trincar e quebrar.<\/p>\n<p><strong>Vinho quente e quent\u00e3o<\/strong><\/p>\n<p>Cuidado com o choque t\u00e9rmico. A bebida ou alimento quando muito quente n\u00e3o oferecem risco imediato de trincar ou danificar o dente. O que pode trincar o dente \u00e9 a combina\u00e7\u00e3o do quente com o gelado. Como por exemplo, tomar um vinho quente seguido de um copo de cerveja. Ou tomar um caldo quente e beber \u00e1gua gelada em seguida. Espere alguns minutos, deixe a temperatura voltar ao normal para consumir algo gelado.<\/p>\n<p>Esteja em dia com seu sorriso, caso n\u00e3o tenha feito uma consulta preventiva com seu dentista nos \u00faltimos seis meses, clique aqui e evite surpresas.<\/p>","protected":false},"excerpt":{"rendered":"<div class=\"entry-summary\">\n<div class=\"entry-summary\">\nNum piscar de olhos chegamos ao meio do ano! Ufa, j\u00e1? O m\u00eas de junho nos traz, al\u00e9m&hellip;\n<\/div>\n<div class=\"link-more\"><a href=\"https:\/\/liraodonto.com.br\/es\/festa-junina-cuidados-com-os-alimentos-tipicos-dessa-temporada\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &ldquo;Festa junina \u2013 cuidados com os alimentos t\u00edpicos dessa temporada&rdquo;<\/span>&hellip;<\/a><\/div>\n<\/div>\n<div class=\"link-more\"><a href=\"https:\/\/liraodonto.com.br\/es\/festa-junina-cuidados-com-os-alimentos-tipicos-dessa-temporada\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &ldquo;Festa junina \u2013 cuidados com os alimentos t\u00edpicos dessa temporada&rdquo;<\/span>&hellip;<\/a><\/div>","protected":false},"author":1,"featured_media":4004,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_joinchat":[],"footnotes":""},"categories":[128],"tags":[],"class_list":["post-4003","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dicas","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Festa junina \u2013 cuidados com os alimentos t\u00edpicos dessa temporada<\/title>\n<meta name=\"description\" content=\"Festa junina - cuidados com os alimentos t\u00edpicos dessa temporada. O m\u00eas de junho nos traz, al\u00e9m do friozinho, as festas juninas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/liraodonto.com.br\/es\/festa-junina-cuidados-com-os-alimentos-tipicos-dessa-temporada\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Festa junina \u2013 cuidados com os alimentos t\u00edpicos dessa temporada\" \/>\n<meta property=\"og:description\" content=\"Festa junina - cuidados com os alimentos t\u00edpicos dessa temporada. O m\u00eas de junho nos traz, al\u00e9m do friozinho, as festas juninas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/liraodonto.com.br\/es\/festa-junina-cuidados-com-os-alimentos-tipicos-dessa-temporada\/\" \/>\n<meta property=\"og:site_name\" content=\"Lira Odonto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/liraodonto\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-19T19:58:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-06-19T20:09:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/liraodonto.com.br\/wp-content\/uploads\/2018\/06\/destaque-festa-junina.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1326\" \/>\n\t<meta property=\"og:image:height\" content=\"928\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/liraodonto.com.br\\\/festa-junina-cuidados-com-os-alimentos-tipicos-dessa-temporada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/liraodonto.com.br\\\/festa-junina-cuidados-com-os-alimentos-tipicos-dessa-temporada\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/liraodonto.com.br\\\/#\\\/schema\\\/person\\\/7865a55a52ea4145ee48ac121cf706da\"},\"headline\":\"Festa junina \u2013 cuidados com os alimentos t\u00edpicos dessa temporada\",\"datePublished\":\"2018-06-19T19:58:21+00:00\",\"dateModified\":\"2018-06-19T20:09:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/liraodonto.com.br\\\/festa-junina-cuidados-com-os-alimentos-tipicos-dessa-temporada\\\/\"},\"wordCount\":644,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/liraodonto.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/liraodonto.com.br\\\/festa-junina-cuidados-com-os-alimentos-tipicos-dessa-temporada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/liraodonto.com.br\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/destaque-festa-junina.jpg\",\"articleSection\":[\"Dicas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/liraodonto.com.br\\\/festa-junina-cuidados-com-os-alimentos-tipicos-dessa-temporada\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/liraodonto.com.br\\\/festa-junina-cuidados-com-os-alimentos-tipicos-dessa-temporada\\\/\",\"url\":\"https:\\\/\\\/liraodonto.com.br\\\/festa-junina-cuidados-com-os-alimentos-tipicos-dessa-temporada\\\/\",\"name\":\"Festa junina \u2013 cuidados com os alimentos t\u00edpicos dessa temporada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/liraodonto.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/liraodonto.com.br\\\/festa-junina-cuidados-com-os-alimentos-tipicos-dessa-temporada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/liraodonto.com.br\\\/festa-junina-cuidados-com-os-alimentos-tipicos-dessa-temporada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/liraodonto.com.br\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/destaque-festa-junina.jpg\",\"datePublished\":\"2018-06-19T19:58:21+00:00\",\"dateModified\":\"2018-06-19T20:09:06+00:00\",\"description\":\"Festa junina - cuidados com os alimentos t\u00edpicos dessa temporada. O m\u00eas de junho nos traz, al\u00e9m do friozinho, as festas juninas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/liraodonto.com.br\\\/festa-junina-cuidados-com-os-alimentos-tipicos-dessa-temporada\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/liraodonto.com.br\\\/festa-junina-cuidados-com-os-alimentos-tipicos-dessa-temporada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/liraodonto.com.br\\\/festa-junina-cuidados-com-os-alimentos-tipicos-dessa-temporada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/liraodonto.com.br\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/destaque-festa-junina.jpg\",\"contentUrl\":\"https:\\\/\\\/liraodonto.com.br\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/destaque-festa-junina.jpg\",\"width\":1326,\"height\":928},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/liraodonto.com.br\\\/festa-junina-cuidados-com-os-alimentos-tipicos-dessa-temporada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/liraodonto.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Festa junina \u2013 cuidados com os alimentos t\u00edpicos dessa temporada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/liraodonto.com.br\\\/#website\",\"url\":\"https:\\\/\\\/liraodonto.com.br\\\/\",\"name\":\"Lira Odonto\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/liraodonto.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/liraodonto.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/liraodonto.com.br\\\/#organization\",\"name\":\"Lira Odonto\",\"url\":\"https:\\\/\\\/liraodonto.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/liraodonto.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/liraodonto.com.br\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/cropped-cropped-lira_odonto_site.png\",\"contentUrl\":\"https:\\\/\\\/liraodonto.com.br\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/cropped-cropped-lira_odonto_site.png\",\"width\":200,\"height\":46,\"caption\":\"Lira Odonto\"},\"image\":{\"@id\":\"https:\\\/\\\/liraodonto.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/liraodonto\\\/\",\"https:\\\/\\\/www.instagram.com\\\/liraodonto\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/liraodonto.com.br\\\/#\\\/schema\\\/person\\\/7865a55a52ea4145ee48ac121cf706da\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3c1a2125ec84d3a56a41750928acd3aaa12fb3f33ed34573b00ebe6ce0f53018?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3c1a2125ec84d3a56a41750928acd3aaa12fb3f33ed34573b00ebe6ce0f53018?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3c1a2125ec84d3a56a41750928acd3aaa12fb3f33ed34573b00ebe6ce0f53018?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/liraodonto.com.br\\\/es\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Festa junina \u2013 cuidados com os alimentos t\u00edpicos dessa temporada","description":"Festa junina - cuidados com os alimentos t\u00edpicos dessa temporada. O m\u00eas de junho nos traz, al\u00e9m do friozinho, as festas juninas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/liraodonto.com.br\/es\/festa-junina-cuidados-com-os-alimentos-tipicos-dessa-temporada\/","og_locale":"es_ES","og_type":"article","og_title":"Festa junina \u2013 cuidados com os alimentos t\u00edpicos dessa temporada","og_description":"Festa junina - cuidados com os alimentos t\u00edpicos dessa temporada. O m\u00eas de junho nos traz, al\u00e9m do friozinho, as festas juninas.","og_url":"https:\/\/liraodonto.com.br\/es\/festa-junina-cuidados-com-os-alimentos-tipicos-dessa-temporada\/","og_site_name":"Lira Odonto","article_publisher":"https:\/\/www.facebook.com\/liraodonto\/","article_published_time":"2018-06-19T19:58:21+00:00","article_modified_time":"2018-06-19T20:09:06+00:00","og_image":[{"width":1326,"height":928,"url":"https:\/\/liraodonto.com.br\/wp-content\/uploads\/2018\/06\/destaque-festa-junina.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/liraodonto.com.br\/festa-junina-cuidados-com-os-alimentos-tipicos-dessa-temporada\/#article","isPartOf":{"@id":"https:\/\/liraodonto.com.br\/festa-junina-cuidados-com-os-alimentos-tipicos-dessa-temporada\/"},"author":{"name":"admin","@id":"https:\/\/liraodonto.com.br\/#\/schema\/person\/7865a55a52ea4145ee48ac121cf706da"},"headline":"Festa junina \u2013 cuidados com os alimentos t\u00edpicos dessa temporada","datePublished":"2018-06-19T19:58:21+00:00","dateModified":"2018-06-19T20:09:06+00:00","mainEntityOfPage":{"@id":"https:\/\/liraodonto.com.br\/festa-junina-cuidados-com-os-alimentos-tipicos-dessa-temporada\/"},"wordCount":644,"commentCount":0,"publisher":{"@id":"https:\/\/liraodonto.com.br\/#organization"},"image":{"@id":"https:\/\/liraodonto.com.br\/festa-junina-cuidados-com-os-alimentos-tipicos-dessa-temporada\/#primaryimage"},"thumbnailUrl":"https:\/\/liraodonto.com.br\/wp-content\/uploads\/2018\/06\/destaque-festa-junina.jpg","articleSection":["Dicas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/liraodonto.com.br\/festa-junina-cuidados-com-os-alimentos-tipicos-dessa-temporada\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/liraodonto.com.br\/festa-junina-cuidados-com-os-alimentos-tipicos-dessa-temporada\/","url":"https:\/\/liraodonto.com.br\/festa-junina-cuidados-com-os-alimentos-tipicos-dessa-temporada\/","name":"Festa junina \u2013 cuidados com os alimentos t\u00edpicos dessa temporada","isPartOf":{"@id":"https:\/\/liraodonto.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/liraodonto.com.br\/festa-junina-cuidados-com-os-alimentos-tipicos-dessa-temporada\/#primaryimage"},"image":{"@id":"https:\/\/liraodonto.com.br\/festa-junina-cuidados-com-os-alimentos-tipicos-dessa-temporada\/#primaryimage"},"thumbnailUrl":"https:\/\/liraodonto.com.br\/wp-content\/uploads\/2018\/06\/destaque-festa-junina.jpg","datePublished":"2018-06-19T19:58:21+00:00","dateModified":"2018-06-19T20:09:06+00:00","description":"Festa junina - cuidados com os alimentos t\u00edpicos dessa temporada. O m\u00eas de junho nos traz, al\u00e9m do friozinho, as festas juninas.","breadcrumb":{"@id":"https:\/\/liraodonto.com.br\/festa-junina-cuidados-com-os-alimentos-tipicos-dessa-temporada\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/liraodonto.com.br\/festa-junina-cuidados-com-os-alimentos-tipicos-dessa-temporada\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/liraodonto.com.br\/festa-junina-cuidados-com-os-alimentos-tipicos-dessa-temporada\/#primaryimage","url":"https:\/\/liraodonto.com.br\/wp-content\/uploads\/2018\/06\/destaque-festa-junina.jpg","contentUrl":"https:\/\/liraodonto.com.br\/wp-content\/uploads\/2018\/06\/destaque-festa-junina.jpg","width":1326,"height":928},{"@type":"BreadcrumbList","@id":"https:\/\/liraodonto.com.br\/festa-junina-cuidados-com-os-alimentos-tipicos-dessa-temporada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/liraodonto.com.br\/"},{"@type":"ListItem","position":2,"name":"Festa junina \u2013 cuidados com os alimentos t\u00edpicos dessa temporada"}]},{"@type":"WebSite","@id":"https:\/\/liraodonto.com.br\/#website","url":"https:\/\/liraodonto.com.br\/","name":"Lira Odonto","description":"","publisher":{"@id":"https:\/\/liraodonto.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/liraodonto.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/liraodonto.com.br\/#organization","name":"Lira Odonto","url":"https:\/\/liraodonto.com.br\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/liraodonto.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/liraodonto.com.br\/wp-content\/uploads\/2016\/04\/cropped-cropped-lira_odonto_site.png","contentUrl":"https:\/\/liraodonto.com.br\/wp-content\/uploads\/2016\/04\/cropped-cropped-lira_odonto_site.png","width":200,"height":46,"caption":"Lira Odonto"},"image":{"@id":"https:\/\/liraodonto.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/liraodonto\/","https:\/\/www.instagram.com\/liraodonto\/"]},{"@type":"Person","@id":"https:\/\/liraodonto.com.br\/#\/schema\/person\/7865a55a52ea4145ee48ac121cf706da","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3c1a2125ec84d3a56a41750928acd3aaa12fb3f33ed34573b00ebe6ce0f53018?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3c1a2125ec84d3a56a41750928acd3aaa12fb3f33ed34573b00ebe6ce0f53018?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3c1a2125ec84d3a56a41750928acd3aaa12fb3f33ed34573b00ebe6ce0f53018?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/liraodonto.com.br\/es\/author\/admin\/"}]}},"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/liraodonto.com.br\/es\/wp-json\/wp\/v2\/posts\/4003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/liraodonto.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/liraodonto.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/liraodonto.com.br\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/liraodonto.com.br\/es\/wp-json\/wp\/v2\/comments?post=4003"}],"version-history":[{"count":1,"href":"https:\/\/liraodonto.com.br\/es\/wp-json\/wp\/v2\/posts\/4003\/revisions"}],"predecessor-version":[{"id":4006,"href":"https:\/\/liraodonto.com.br\/es\/wp-json\/wp\/v2\/posts\/4003\/revisions\/4006"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/liraodonto.com.br\/es\/wp-json\/wp\/v2\/media\/4004"}],"wp:attachment":[{"href":"https:\/\/liraodonto.com.br\/es\/wp-json\/wp\/v2\/media?parent=4003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/liraodonto.com.br\/es\/wp-json\/wp\/v2\/categories?post=4003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/liraodonto.com.br\/es\/wp-json\/wp\/v2\/tags?post=4003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}